{"id":2144,"date":"2022-05-17T21:30:15","date_gmt":"2022-05-17T21:30:15","guid":{"rendered":"https:\/\/geo-webonline.com\/?page_id=2144"},"modified":"2025-04-06T17:32:44","modified_gmt":"2025-04-06T17:32:44","slug":"taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno","status":"publish","type":"page","link":"https:\/\/geo-webonline.com\/en\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\/","title":{"rendered":"Slopes in residual materials: geotechnical exploration and geomechanical design parameters"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2144\" class=\"elementor elementor-2144\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b23578 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b23578\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dfaf88e\" data-id=\"dfaf88e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-654f236 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"654f236\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-7da78dc\" href=\"https:\/\/www.facebook.com\/Geo-Web-100977118794652\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-fe85f2d\" href=\"https:\/\/twitter.com\/geowebonline\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-a21533a\" href=\"https:\/\/www.instagram.com\/geowebonline\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-8544528\" href=\"https:\/\/www.linkedin.com\/in\/alvaro-boiero-37bb4348\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32755b9 elementor-section-full_width elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"32755b9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-db5908d\" data-id=\"db5908d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f4545c elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-image\" data-id=\"0f4545c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"582\" height=\"277\" src=\"https:\/\/geo-webonline.com\/wp-content\/uploads\/2024\/07\/logosgeonewalvaro.png\" class=\"attachment-large size-large wp-image-3338\" alt=\"\" srcset=\"https:\/\/geo-webonline.com\/wp-content\/uploads\/2024\/07\/logosgeonewalvaro.png 582w, https:\/\/geo-webonline.com\/wp-content\/uploads\/2024\/07\/logosgeonewalvaro-300x143.png 300w, https:\/\/geo-webonline.com\/wp-content\/uploads\/2024\/07\/logosgeonewalvaro-18x9.png 18w\" sizes=\"(max-width: 582px) 100vw, 582px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9792d68\" data-id=\"9792d68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1715971 elementor-nav-menu__align-center elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"1715971\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-1715971\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-1163\"><a href=\"https:\/\/geo-webonline.com\/en\/\" class=\"elementor-item\">Inicio<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1164\"><a href=\"https:\/\/geo-webonline.com\/en\/quien-soy\/\" class=\"elementor-item\">geo<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1165\"><a href=\"https:\/\/geo-webonline.com\/en\/quieres-saber-mas\/\" class=\"elementor-item\">geo-info<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1169\"><a href=\"https:\/\/geo-webonline.com\/en\/fundaciones-2\/\" class=\"elementor-sub-item\">Fundaciones<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-386\"><a href=\"https:\/\/geo-webonline.com\/en\/mecanica-de-suelos\/\" class=\"elementor-sub-item\">Mec\u00e1nica de Suelos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-387\"><a href=\"https:\/\/geo-webonline.com\/en\/muros\/\" class=\"elementor-sub-item\">Muros<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-383\"><a href=\"https:\/\/geo-webonline.com\/en\/estabilidad-de-talues\/\" class=\"elementor-sub-item\">Estabilidad de Taludes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-381\"><a href=\"https:\/\/geo-webonline.com\/en\/aguas-subterraneas\/\" class=\"elementor-sub-item\">Aguas Subterraneas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-388\"><a href=\"https:\/\/geo-webonline.com\/en\/topicos-especiales\/\" class=\"elementor-sub-item\">T\u00f3picos Especiales<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4247\"><a href=\"https:\/\/geo-webonline.com\/en\/terremoto-en-venezuela\/\" class=\"elementor-sub-item\">Terremoto en Venezuela<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1166\"><a href=\"https:\/\/geo-webonline.com\/en\/e-learning\/\" class=\"elementor-item\">E-learning<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2318\"><a href=\"https:\/\/geo-webonline.com\/en\/servicios-de-consultoria\/\" class=\"elementor-item\">Servicios de consultor\u00eda<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3224\"><a href=\"https:\/\/geo-webonline.com\/en\/proyecto-geotecnico\/\" class=\"elementor-item\">Proyectos geot\u00e9cnicos<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1168\"><a href=\"https:\/\/geo-webonline.com\/en\/contacto\/\" class=\"elementor-item\">Contacto<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-1715971\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-1163\"><a href=\"https:\/\/geo-webonline.com\/en\/\" class=\"elementor-item\" tabindex=\"-1\">Inicio<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1164\"><a href=\"https:\/\/geo-webonline.com\/en\/quien-soy\/\" class=\"elementor-item\" tabindex=\"-1\">geo<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1165\"><a href=\"https:\/\/geo-webonline.com\/en\/quieres-saber-mas\/\" class=\"elementor-item\" tabindex=\"-1\">geo-info<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1169\"><a href=\"https:\/\/geo-webonline.com\/en\/fundaciones-2\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Fundaciones<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-386\"><a href=\"https:\/\/geo-webonline.com\/en\/mecanica-de-suelos\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Mec\u00e1nica de Suelos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-387\"><a href=\"https:\/\/geo-webonline.com\/en\/muros\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Muros<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-383\"><a href=\"https:\/\/geo-webonline.com\/en\/estabilidad-de-talues\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Estabilidad de Taludes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-381\"><a href=\"https:\/\/geo-webonline.com\/en\/aguas-subterraneas\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Aguas Subterraneas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-388\"><a href=\"https:\/\/geo-webonline.com\/en\/topicos-especiales\/\" class=\"elementor-sub-item\" tabindex=\"-1\">T\u00f3picos Especiales<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4247\"><a href=\"https:\/\/geo-webonline.com\/en\/terremoto-en-venezuela\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Terremoto en Venezuela<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1166\"><a href=\"https:\/\/geo-webonline.com\/en\/e-learning\/\" class=\"elementor-item\" tabindex=\"-1\">E-learning<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2318\"><a href=\"https:\/\/geo-webonline.com\/en\/servicios-de-consultoria\/\" class=\"elementor-item\" tabindex=\"-1\">Servicios de consultor\u00eda<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3224\"><a href=\"https:\/\/geo-webonline.com\/en\/proyecto-geotecnico\/\" class=\"elementor-item\" tabindex=\"-1\">Proyectos geot\u00e9cnicos<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1168\"><a href=\"https:\/\/geo-webonline.com\/en\/contacto\/\" class=\"elementor-item\" tabindex=\"-1\">Contacto<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab33757 elementor-section-full_width elementor-section-height-min-height elementor-hidden-desktop elementor-section-height-default elementor-section-items-middle\" data-id=\"ab33757\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3050cb3\" data-id=\"3050cb3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b23a545 elementor-widget__width-initial elementor-absolute elementor-widget-mobile__width-initial elementor-hidden-desktop elementor-widget elementor-widget-image\" data-id=\"b23a545\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"582\" height=\"277\" src=\"https:\/\/geo-webonline.com\/wp-content\/uploads\/2024\/07\/logosgeonewalvaro.png\" class=\"attachment-large size-large wp-image-3338\" alt=\"\" srcset=\"https:\/\/geo-webonline.com\/wp-content\/uploads\/2024\/07\/logosgeonewalvaro.png 582w, https:\/\/geo-webonline.com\/wp-content\/uploads\/2024\/07\/logosgeonewalvaro-300x143.png 300w, https:\/\/geo-webonline.com\/wp-content\/uploads\/2024\/07\/logosgeonewalvaro-18x9.png 18w\" sizes=\"(max-width: 582px) 100vw, 582px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e5abfac\" data-id=\"e5abfac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-272e854 elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"272e854\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8d4e268\" data-id=\"8d4e268\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aef14b1 elementor-nav-menu__align-center elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"aef14b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-aef14b1\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-1163\"><a href=\"https:\/\/geo-webonline.com\/en\/\" class=\"elementor-item\">Inicio<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1164\"><a href=\"https:\/\/geo-webonline.com\/en\/quien-soy\/\" class=\"elementor-item\">geo<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1165\"><a href=\"https:\/\/geo-webonline.com\/en\/quieres-saber-mas\/\" class=\"elementor-item\">geo-info<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1169\"><a href=\"https:\/\/geo-webonline.com\/en\/fundaciones-2\/\" class=\"elementor-sub-item\">Fundaciones<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-386\"><a href=\"https:\/\/geo-webonline.com\/en\/mecanica-de-suelos\/\" class=\"elementor-sub-item\">Mec\u00e1nica de Suelos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-387\"><a href=\"https:\/\/geo-webonline.com\/en\/muros\/\" class=\"elementor-sub-item\">Muros<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-383\"><a href=\"https:\/\/geo-webonline.com\/en\/estabilidad-de-talues\/\" class=\"elementor-sub-item\">Estabilidad de Taludes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-381\"><a href=\"https:\/\/geo-webonline.com\/en\/aguas-subterraneas\/\" class=\"elementor-sub-item\">Aguas Subterraneas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-388\"><a href=\"https:\/\/geo-webonline.com\/en\/topicos-especiales\/\" class=\"elementor-sub-item\">T\u00f3picos Especiales<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4247\"><a href=\"https:\/\/geo-webonline.com\/en\/terremoto-en-venezuela\/\" class=\"elementor-sub-item\">Terremoto en Venezuela<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1166\"><a href=\"https:\/\/geo-webonline.com\/en\/e-learning\/\" class=\"elementor-item\">E-learning<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2318\"><a href=\"https:\/\/geo-webonline.com\/en\/servicios-de-consultoria\/\" class=\"elementor-item\">Servicios de consultor\u00eda<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3224\"><a href=\"https:\/\/geo-webonline.com\/en\/proyecto-geotecnico\/\" class=\"elementor-item\">Proyectos geot\u00e9cnicos<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1168\"><a href=\"https:\/\/geo-webonline.com\/en\/contacto\/\" class=\"elementor-item\">Contacto<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-aef14b1\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-1163\"><a href=\"https:\/\/geo-webonline.com\/en\/\" class=\"elementor-item\" tabindex=\"-1\">Inicio<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1164\"><a href=\"https:\/\/geo-webonline.com\/en\/quien-soy\/\" class=\"elementor-item\" tabindex=\"-1\">geo<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1165\"><a href=\"https:\/\/geo-webonline.com\/en\/quieres-saber-mas\/\" class=\"elementor-item\" tabindex=\"-1\">geo-info<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1169\"><a href=\"https:\/\/geo-webonline.com\/en\/fundaciones-2\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Fundaciones<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-386\"><a href=\"https:\/\/geo-webonline.com\/en\/mecanica-de-suelos\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Mec\u00e1nica de Suelos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-387\"><a href=\"https:\/\/geo-webonline.com\/en\/muros\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Muros<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-383\"><a href=\"https:\/\/geo-webonline.com\/en\/estabilidad-de-talues\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Estabilidad de Taludes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-381\"><a href=\"https:\/\/geo-webonline.com\/en\/aguas-subterraneas\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Aguas Subterraneas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-388\"><a href=\"https:\/\/geo-webonline.com\/en\/topicos-especiales\/\" class=\"elementor-sub-item\" tabindex=\"-1\">T\u00f3picos Especiales<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4247\"><a href=\"https:\/\/geo-webonline.com\/en\/terremoto-en-venezuela\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Terremoto en Venezuela<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1166\"><a href=\"https:\/\/geo-webonline.com\/en\/e-learning\/\" class=\"elementor-item\" tabindex=\"-1\">E-learning<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2318\"><a href=\"https:\/\/geo-webonline.com\/en\/servicios-de-consultoria\/\" class=\"elementor-item\" tabindex=\"-1\">Servicios de consultor\u00eda<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3224\"><a href=\"https:\/\/geo-webonline.com\/en\/proyecto-geotecnico\/\" class=\"elementor-item\" tabindex=\"-1\">Proyectos geot\u00e9cnicos<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1168\"><a href=\"https:\/\/geo-webonline.com\/en\/contacto\/\" class=\"elementor-item\" tabindex=\"-1\">Contacto<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5aa5078 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5aa5078\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-51d2394\" data-id=\"51d2394\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d54f72 elementor-widget elementor-widget-heading\" data-id=\"9d54f72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Taludes en materiales residuales: exploraci\u00f3n geot\u00e9cnica y par\u00e1metros geomec\u00e1nicos de dise\u00f1o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87825fd elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"87825fd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-96778ea\" data-id=\"96778ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b337a2a elementor-widget elementor-widget-text-editor\" data-id=\"b337a2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>\u00bfCu\u00e1les debe ser los objetivos al realizar la exploraci\u00f3n geot\u00e9cnica para el an\u00e1lisis de taludes en materiales residuales? \u00bfQu\u00e9 informaci\u00f3n m\u00ednima debe obtenerse en campo? \u00bfQu\u00e9 ensayos de laboratorio deben realizarse para la obtenci\u00f3n de par\u00e1metros geomec\u00e1nicos de dise\u00f1o? \u00bfQu\u00e9 criterios aplicar? Estas son algunas de las preguntas que pueden aparecer en proyectos que involucran estabilidad de taludes en materiales residuales. As\u00ed que vamos a tratar de ofrecer algunas respuestas\u2026<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79013c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79013c7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-181f252\" data-id=\"181f252\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf371d6 elementor-toc--minimized-on-tablet elementor-widget elementor-widget-table-of-contents\" data-id=\"bf371d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h3&quot;],&quot;exclude_headings_by_selector&quot;:[],&quot;no_headings_message&quot;:&quot;No headings were found on this page.&quot;,&quot;marker_view&quot;:&quot;numbers&quot;,&quot;minimize_box&quot;:&quot;yes&quot;,&quot;minimized_on&quot;:&quot;tablet&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h4 class=\"elementor-toc__header-title\">\n\t\t\t\tContenido\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--expand\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__bf371d6\" aria-expanded=\"true\" aria-label=\"Open table of contents\"><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/div>\n\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--collapse\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__bf371d6\" aria-expanded=\"true\" aria-label=\"Close table of contents\"><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__bf371d6\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<i class=\"elementor-toc__spinner eicon-animation-spin eicon-loading\" aria-hidden=\"true\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b7b75b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9b7b75b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0652fef\" data-id=\"0652fef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84ba0a3 elementor-widget elementor-widget-heading\" data-id=\"84ba0a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Objetivos de la investigaci\u00f3n geot\u00e9cnica <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db16ae7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"db16ae7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7188975\" data-id=\"7188975\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d68ee8f elementor-widget elementor-widget-text-editor\" data-id=\"d68ee8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cuando se desarrollan proyectos que involucran la estabilidad de taludes en suelos residuales, lo primero que se vislumbra es que la investigaci\u00f3n geot\u00e9cnica de este tipo de materiales empleando los m\u00e9todos tradicionales (es decir, en base a las herramientas y equipos disponibles en la gran mayor\u00eda de las empresas geot\u00e9cnicas), es un tanto complicada, fundamentalmente por dos razones: A) porque usualmente estos materiales se encuentran parcialmente saturados; y B) porque la geolog\u00eda del talud suele ser compleja.<\/p><p>\u00a0<\/p><p>\u00bfCu\u00e1les deben ser, entonces, los objetivos principales de la investigaci\u00f3n geot\u00e9cnica en estos casos? B\u00e1sicamente, deben orientarse a la obtenci\u00f3n de informaci\u00f3n sobre:<\/p><p>\u00a0<\/p><ol><li>Caracterizaci\u00f3n del perfil de meteorizaci\u00f3n.<\/li><li>Localizaci\u00f3n de las principales estructuras (fallas, diaclasas, estructuras heredadas).<\/li><li>Determinaci\u00f3n de las condiciones del agua subterr\u00e1nea.<\/li><li>Establecimiento del modo de falla m\u00e1s probable y de los par\u00e1metros de resistencia en la superficie de falla.<\/li><\/ol><p>\u00a0<\/p><p>Es importante considerar que, dada la complejidad del comportamiento geot\u00e9cnico de los suelos residuales (particularmente en taludes), nunca deben perderse de vista estos objetivos durante la investigaci\u00f3n, puesto que los mismos incluyen la informaci\u00f3n b\u00e1sica necesaria para la adecuada caracterizaci\u00f3n y comprensi\u00f3n del problema, as\u00ed como para la estimaci\u00f3n de los par\u00e1metros geomec\u00e1nicos requeridos en cualquier modelo del talud que se desarrolle para analizar su comportamiento.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59f2e4e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"59f2e4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b9cddd3\" data-id=\"b9cddd3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e1de73 elementor-widget elementor-widget-heading\" data-id=\"7e1de73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Exploraci\u00f3n de campo<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b70bdb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5b70bdb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-296f1c5\" data-id=\"296f1c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0966daf elementor-widget elementor-widget-text-editor\" data-id=\"0966daf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La exploraci\u00f3n geot\u00e9cnica de campo usualmente se lleva a cabo a trav\u00e9s de dos actividades generales (Amundaray, 1985):<\/p><p>\u00a0<\/p><ol><li>Una exploraci\u00f3n geol\u00f3gica detallada (la cual implica un levantamiento de campo).<\/li><li>La realizaci\u00f3n de perforaciones, a fin de confirmar el perfil de meteorizaci\u00f3n y de recuperar muestras para ensayos de laboratorio especiales.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8dc8395 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8dc8395\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25817d4\" data-id=\"25817d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c45a0ce elementor-widget elementor-widget-image\" data-id=\"c45a0ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/geo-webonline.com\/wp-content\/uploads\/2022\/05\/figura1.jpg\" class=\"attachment-large size-large wp-image-2146\" alt=\"\" srcset=\"https:\/\/geo-webonline.com\/wp-content\/uploads\/2022\/05\/figura1.jpg 933w, https:\/\/geo-webonline.com\/wp-content\/uploads\/2022\/05\/figura1-300x200.jpg 300w, https:\/\/geo-webonline.com\/wp-content\/uploads\/2022\/05\/figura1-768x511.jpg 768w, https:\/\/geo-webonline.com\/wp-content\/uploads\/2022\/05\/figura1-18x12.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b3a920a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b3a920a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ddac39\" data-id=\"9ddac39\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3deffb elementor-widget elementor-widget-text-editor\" data-id=\"f3deffb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Figura 1<\/strong> Objetivos de la investigaci\u00f3n geot\u00e9cnica para an\u00e1lisis de estabilidad de taludes en suelos residuales<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b9c0f18 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b9c0f18\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-005f0f8\" data-id=\"005f0f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac739e2 elementor-widget elementor-widget-text-editor\" data-id=\"ac739e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Algunos autores recomiendan el empleo de m\u00e9todos geof\u00edsicos (tales como refracci\u00f3n s\u00edsmica o resistividad el\u00e9ctrica, por ejemplo), a partir de los cuales podr\u00eda evaluarse de manera aproximada el espesor de los suelos residuales, en base a la estimaci\u00f3n de la profundidad a la que se encuentra la roca fresca y a los cambios en la densidad del medio que es posible determinar empleando estos m\u00e9todos. Sin embargo, vale destacar que la Geof\u00edsica debe ser aplicada con cautela en estos casos, debido a la dif\u00edcil interpretaci\u00f3n de la data obtenida, que se dificulta significativamente para terrenos inclinados.<\/p><p>\u00a0<\/p><p>Por lo tanto, es m\u00e1s conveniente llevar adelante una exploraci\u00f3n geol\u00f3gica detallada, que permita identificar claramente los diferentes horizontes de meteorizaci\u00f3n. Dicha exploraci\u00f3n debe complementarse con perforaciones geot\u00e9cnicas, de di\u00e1metro NX o superior (de manera que pueda determinarse el <em>Rock Quality Designation &#8211;<\/em>RQD- cuando se detecte la roca). Adicionalmente, es recomendable la realizaci\u00f3n del ensayo SPT (<em>Standard Penetration Test<\/em>), hasta donde sea posible \u201cen seco\u201d, a fin de tener una idea de la resistencia de los materiales en el perfil de meteorizaci\u00f3n, as\u00ed como para detectar la presencia de agua en el subsuelo (Amundaray, 1995).<\/p><p>\u00a0<\/p><p>Un punto siempre complicado es determinar el n\u00famero de perforaciones a realizar. Como criterio general, el n\u00famero de sondeos depender\u00e1 del grado de heterogeneidad del talud, y en todos los casos deber\u00e1n alcanzar la roca fresca. Ello implica que las perforaciones deben ejecutarse <em>luego<\/em> del levantamiento geol\u00f3gico, dado que la ubicaci\u00f3n de las mismas debe establecerse en base a la informaci\u00f3n derivada de dicho levantamiento.<\/p><p>\u00a0<\/p><p>De lo anterior se deduce que, para proyectos que involucren an\u00e1lisis de estabilidad de taludes en suelos residuales, en el equipo de trabajo debe participar un Ingeniero Ge\u00f3logo, puesto que, a diferencia de otro tipo de proyectos civiles menos complejos, la Geolog\u00eda juega un papel muy importante en estos casos. Este comentario podr\u00eda resultar obvio, pero se considera pertinente porque, en muchas ocasiones, se subestiman las implicaciones asociadas a an\u00e1lisis de estabilidad de taludes en materiales residuales, y los desarrollan profesionales que no tienen toda la preparaci\u00f3n para afrontarlos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83a3647 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"83a3647\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2eb3be0\" data-id=\"2eb3be0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0e2f0f elementor-widget elementor-widget-heading\" data-id=\"d0e2f0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Estimaci\u00f3n de par\u00e1metros geot\u00e9cnicos de dise\u00f1o<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-361a6ab elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"361a6ab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-431cbcf\" data-id=\"431cbcf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-999ca3d elementor-widget elementor-widget-text-editor\" data-id=\"999ca3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Como se mencion\u00f3 anteriormente, los suelos residuales se encuentran, durante gran parte del a\u00f1o, bajo condiciones de saturaci\u00f3n parcial. De acuerdo a esto, lo l\u00f3gico ser\u00eda pensar en que deber\u00edan aplicarse los principios de la Mec\u00e1nica de los Suelos Parcialmente Saturados para realizar cualquier an\u00e1lisis que tenga que ver con este tipo de materiales. Y, efectivamente, es as\u00ed.<\/p><p>\u00a0<\/p><p>Sin embargo, en la pr\u00e1ctica existe una desventaja: los laboratorios disponibles en la gran mayor\u00eda de las empresas geot\u00e9cnicas (que pudi\u00e9ramos llamar \u201ccomerciales\u201d, en contraposici\u00f3n a los laboratorios de algunas universidades donde se llevan adelante trabajos de investigaci\u00f3n), no poseen los instrumentos para medir succi\u00f3n en muestras de suelo o roca.<\/p><p>\u00a0<\/p><p>Esto es as\u00ed porque la Mec\u00e1nica de Suelos tradicional (la que se emplea com\u00fanmente en an\u00e1lisis rutinarios) es la \u201cMec\u00e1nica de los Suelos Saturados\u201d, dado que en muchos de los ensayos que se realizan, se agrega agua a la muestra. Incluso es com\u00fan saturar la muestra para efectuar ensayos de resistencia al corte, debido que el caso saturado es el m\u00e1s desfavorable, en el que se obtendr\u00e1n los peores par\u00e1metros de resistencia y deformaci\u00f3n.<\/p><p>\u00a0<\/p><p>De acuerdo a lo anterior, para la gran mayor\u00eda de los proyectos, se recomienda llevar a cabo los an\u00e1lisis de estabilidad considerando <em>condiciones saturadas <\/em>y<em> la mayor altura posible del nivel de agua en el talud<\/em> (es decir, que el nivel de agua alcanza la superficie). Dado que este caso incluye las condiciones m\u00e1s desfavorables para el talud, el an\u00e1lisis permitir\u00e1 estimar el factor de seguridad (FS) m\u00e1s bajo y conservador. As\u00ed, si en estos an\u00e1lisis se obtiene un FS mayor o igual a 1,5, puede esperarse que el talud analizado se mantenga estable, a\u00fan bajo las peores condiciones de lluvia.<\/p><p>\u00a0<\/p><p>Los par\u00e1metros de resistencia a utilizar en estos an\u00e1lisis, pueden estimarse mediante la realizaci\u00f3n de ensayos triaxiales no consolidados no drenados (TX UU), bajo condiciones saturadas. Tambi\u00e9n puede emplearse como alternativa el ensayo de corte directo (CD), m\u00e1s econ\u00f3mico y r\u00e1pido que el TX UU.<\/p><p>\u00a0<\/p><p>Las muestras para realizar estos ensayos se obtienen de las perforaciones, las cuales, como se mencion\u00f3 anteriormente, deben realizarse con di\u00e1metro NX o superior. Tambi\u00e9n es posible, aunque menos usual, extraer muestras de calicatas, o muestras directamente talladas en el talud.<\/p><p>\u00a0<\/p><p>Por otro lado, cabe mencionar que, para la realizaci\u00f3n de estimaciones preliminares, pueden emplearse correlaciones basadas en informaci\u00f3n obtenida de taludes en formaciones geol\u00f3gicas similares a las del sitio en estudio. La Figura 2, desarrollada por Schnaid (2005, 2009) es un buen ejemplo de estas correlaciones.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-969db29 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"969db29\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3e86566\" data-id=\"3e86566\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-044ec51 elementor-widget elementor-widget-image\" data-id=\"044ec51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"413\" src=\"https:\/\/geo-webonline.com\/wp-content\/uploads\/2022\/05\/figura2-1024x528.jpg\" class=\"attachment-large size-large wp-image-2147\" alt=\"\" srcset=\"https:\/\/geo-webonline.com\/wp-content\/uploads\/2022\/05\/figura2-1024x528.jpg 1024w, https:\/\/geo-webonline.com\/wp-content\/uploads\/2022\/05\/figura2-300x155.jpg 300w, https:\/\/geo-webonline.com\/wp-content\/uploads\/2022\/05\/figura2-768x396.jpg 768w, https:\/\/geo-webonline.com\/wp-content\/uploads\/2022\/05\/figura2-18x9.jpg 18w, https:\/\/geo-webonline.com\/wp-content\/uploads\/2022\/05\/figura2.jpg 1257w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8211320 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"8211320\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5290aba\" data-id=\"5290aba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-03b6bd8 elementor-widget elementor-widget-text-editor\" data-id=\"03b6bd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Figura 2<\/strong> Correlaciones para estimar el \u00e1ngulo de fricci\u00f3n interna <em>\u03c6<\/em> y el m\u00f3dulo de corte inicial <em>Go<\/em> para materiales residuales. <em>Ir<\/em> = \u00edndice de rigidez; <em>G =<\/em> m\u00f3dulo de corte; <em>c<\/em> = cohesi\u00f3n; <em>q<\/em> = esfuerzo vertical\u00b8<em>\u03b3 = <\/em>\u00e1ngulo de fricci\u00f3n interna (<em>Fuente<\/em>: Schnaid, 2005-2009. Disponible en <a href=\"https:\/\/www.routledgehandbooks.com\/doi\/10.1201\/b12302-3\">https:\/\/www.routledgehandbooks.com\/doi\/10.1201\/b12302-3<\/a>).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b58276 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4b58276\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-37e2eff\" data-id=\"37e2eff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c75d2d7 elementor-widget elementor-widget-text-editor\" data-id=\"c75d2d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Por supuesto, como en cualquier obra de ingenier\u00eda, todo depender\u00e1 del equilibrio costo-informaci\u00f3n. Si la importancia de la obra lo amerita, y la realizaci\u00f3n de an\u00e1lisis tomando en cuenta condiciones parcialmente saturadas pudiera significar un ahorro importante en estabilizaci\u00f3n, por ejemplo, estos an\u00e1lisis deben llevarse a cabo, en laboratorios especialmente equipados para ello.<\/p><p>\u00a0<\/p><p>En todo caso, el especialista geot\u00e9cnico recomendar\u00e1 qu\u00e9 es lo id\u00f3neo para el proyecto que est\u00e9 realizando. Sin embargo, como se mencion\u00f3 anteriormente, dadas las limitaciones t\u00edpicas de los equipos de laboratorio disponibles para estudios geot\u00e9cnicos rutinarios, la determinaci\u00f3n de <em>par\u00e1metros saturados<\/em> <em>con el nivel m\u00e1s alto de agua<\/em>, es el caso m\u00e1s usual en la pr\u00e1ctica.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d42298c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d42298c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-accd5f3\" data-id=\"accd5f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81365df elementor-widget elementor-widget-heading\" data-id=\"81365df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Referencias<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-537151f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"537151f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-495aa00\" data-id=\"495aa00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f4dca6 elementor-widget elementor-widget-text-editor\" data-id=\"2f4dca6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Amundaray, J. (1985) <strong>\u201cLandslides and stability in residual soils in tropical climates\u201d<\/strong>. Document CE 695 E. Colorado State University. Fort Collins, USA.<\/li><li><a href=\"https:\/\/www.routledgehandbooks.com\/author\/Bujang%20B.K._Huat\">Huat, B.<\/a>,\u00a0<a href=\"https:\/\/www.routledgehandbooks.com\/author\/David%20G._Toll\">Toll<\/a>, D. &amp;\u00a0<a href=\"https:\/\/www.routledgehandbooks.com\/author\/Arun_Prasad\">Prasad<\/a>, A. (2012)\u00a0,<a href=\"https:\/\/www.routledgehandbooks.com\/doi\/10.1201\/b12302\"><strong>&#8220;Handbook of tropical residual soils engineering&#8221;<\/strong>.<strong>\u00a0<\/strong><\/a>Print ISBN:\u00a09780415457316; eBook ISBN:\u00a09780203098325.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f1041a8 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f1041a8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-417cc5c\" data-id=\"417cc5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-506a73c elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"506a73c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-7da78dc\" href=\"https:\/\/www.facebook.com\/Geo-Web-100977118794652\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-fe85f2d\" href=\"https:\/\/twitter.com\/geowebonline\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-ad54125\" href=\"https:\/\/www.linkedin.com\/in\/alvaro-boiero-37bb4348\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-a21533a\" href=\"https:\/\/www.instagram.com\/geowebonline\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aed6a1a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"aed6a1a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-81680cf\" data-id=\"81680cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0dc3c64 elementor-widget elementor-widget-heading\" data-id=\"0dc3c64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2024 - geo Todos los derechos reservados \/ Desarrollo web: lubercba<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Facebook Twitter Instagram Linkedin Taludes en materiales residuales: exploraci\u00f3n geot\u00e9cnica y par\u00e1metros geomec\u00e1nicos de dise\u00f1o \u00bfCu\u00e1les debe ser los objetivos al realizar la exploraci\u00f3n geot\u00e9cnica para el an\u00e1lisis de taludes en materiales residuales? \u00bfQu\u00e9 informaci\u00f3n m\u00ednima debe obtenerse en campo? \u00bfQu\u00e9 ensayos de laboratorio deben realizarse para la obtenci\u00f3n de par\u00e1metros geomec\u00e1nicos de dise\u00f1o? \u00bfQu\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2144","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Taludes en materiales residuales: exploraci\u00f3n geot\u00e9cnica y par\u00e1metros geomec\u00e1nicos de dise\u00f1o -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/geo-webonline.com\/en\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taludes en materiales residuales: exploraci\u00f3n geot\u00e9cnica y par\u00e1metros geomec\u00e1nicos de dise\u00f1o -\" \/>\n<meta property=\"og:description\" content=\"Facebook Twitter Instagram Linkedin Taludes en materiales residuales: exploraci\u00f3n geot\u00e9cnica y par\u00e1metros geomec\u00e1nicos de dise\u00f1o \u00bfCu\u00e1les debe ser los objetivos al realizar la exploraci\u00f3n geot\u00e9cnica para el an\u00e1lisis de taludes en materiales residuales? \u00bfQu\u00e9 informaci\u00f3n m\u00ednima debe obtenerse en campo? \u00bfQu\u00e9 ensayos de laboratorio deben realizarse para la obtenci\u00f3n de par\u00e1metros geomec\u00e1nicos de dise\u00f1o? \u00bfQu\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/geo-webonline.com\/en\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-06T17:32:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/geo-webonline.com\/wp-content\/uploads\/2024\/07\/logosgeonewalvaro.png\" \/>\n\t<meta property=\"og:image:width\" content=\"582\" \/>\n\t<meta property=\"og:image:height\" content=\"277\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/geo-webonline.com\\\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\\\/\",\"url\":\"https:\\\/\\\/geo-webonline.com\\\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\\\/\",\"name\":\"Taludes en materiales residuales: exploraci\u00f3n geot\u00e9cnica y par\u00e1metros geomec\u00e1nicos de dise\u00f1o -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/geo-webonline.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/geo-webonline.com\\\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/geo-webonline.com\\\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/geo-webonline.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logosgeonewalvaro.png\",\"datePublished\":\"2022-05-17T21:30:15+00:00\",\"dateModified\":\"2025-04-06T17:32:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/geo-webonline.com\\\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/geo-webonline.com\\\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/geo-webonline.com\\\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/geo-webonline.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logosgeonewalvaro.png\",\"contentUrl\":\"https:\\\/\\\/geo-webonline.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logosgeonewalvaro.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/geo-webonline.com\\\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/geo-webonline.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Taludes en materiales residuales: exploraci\u00f3n geot\u00e9cnica y par\u00e1metros geomec\u00e1nicos de dise\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/geo-webonline.com\\\/#website\",\"url\":\"https:\\\/\\\/geo-webonline.com\\\/\",\"name\":\"\",\"description\":\"El Blog de Alvaro Boiero\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/geo-webonline.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taludes en materiales residuales: exploraci\u00f3n geot\u00e9cnica y par\u00e1metros geomec\u00e1nicos de dise\u00f1o -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/geo-webonline.com\/en\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\/","og_locale":"en_US","og_type":"article","og_title":"Taludes en materiales residuales: exploraci\u00f3n geot\u00e9cnica y par\u00e1metros geomec\u00e1nicos de dise\u00f1o -","og_description":"Facebook Twitter Instagram Linkedin Taludes en materiales residuales: exploraci\u00f3n geot\u00e9cnica y par\u00e1metros geomec\u00e1nicos de dise\u00f1o \u00bfCu\u00e1les debe ser los objetivos al realizar la exploraci\u00f3n geot\u00e9cnica para el an\u00e1lisis de taludes en materiales residuales? \u00bfQu\u00e9 informaci\u00f3n m\u00ednima debe obtenerse en campo? \u00bfQu\u00e9 ensayos de laboratorio deben realizarse para la obtenci\u00f3n de par\u00e1metros geomec\u00e1nicos de dise\u00f1o? \u00bfQu\u00e9 [&hellip;]","og_url":"https:\/\/geo-webonline.com\/en\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\/","article_modified_time":"2025-04-06T17:32:44+00:00","og_image":[{"width":582,"height":277,"url":"https:\/\/geo-webonline.com\/wp-content\/uploads\/2024\/07\/logosgeonewalvaro.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/geo-webonline.com\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\/","url":"https:\/\/geo-webonline.com\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\/","name":"Taludes en materiales residuales: exploraci\u00f3n geot\u00e9cnica y par\u00e1metros geomec\u00e1nicos de dise\u00f1o -","isPartOf":{"@id":"https:\/\/geo-webonline.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/geo-webonline.com\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\/#primaryimage"},"image":{"@id":"https:\/\/geo-webonline.com\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\/#primaryimage"},"thumbnailUrl":"https:\/\/geo-webonline.com\/wp-content\/uploads\/2024\/07\/logosgeonewalvaro.png","datePublished":"2022-05-17T21:30:15+00:00","dateModified":"2025-04-06T17:32:44+00:00","breadcrumb":{"@id":"https:\/\/geo-webonline.com\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/geo-webonline.com\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/geo-webonline.com\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\/#primaryimage","url":"https:\/\/geo-webonline.com\/wp-content\/uploads\/2024\/07\/logosgeonewalvaro.png","contentUrl":"https:\/\/geo-webonline.com\/wp-content\/uploads\/2024\/07\/logosgeonewalvaro.png"},{"@type":"BreadcrumbList","@id":"https:\/\/geo-webonline.com\/taludes-en-materiales-residuales-exploracion-geotecnica-y-parametros-geomecanicos-de-diseno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/geo-webonline.com\/"},{"@type":"ListItem","position":2,"name":"Taludes en materiales residuales: exploraci\u00f3n geot\u00e9cnica y par\u00e1metros geomec\u00e1nicos de dise\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/geo-webonline.com\/#website","url":"https:\/\/geo-webonline.com\/","name":"","description":"El Blog de Alvaro Boiero","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/geo-webonline.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/geo-webonline.com\/en\/wp-json\/wp\/v2\/pages\/2144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/geo-webonline.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/geo-webonline.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/geo-webonline.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/geo-webonline.com\/en\/wp-json\/wp\/v2\/comments?post=2144"}],"version-history":[{"count":10,"href":"https:\/\/geo-webonline.com\/en\/wp-json\/wp\/v2\/pages\/2144\/revisions"}],"predecessor-version":[{"id":3940,"href":"https:\/\/geo-webonline.com\/en\/wp-json\/wp\/v2\/pages\/2144\/revisions\/3940"}],"wp:attachment":[{"href":"https:\/\/geo-webonline.com\/en\/wp-json\/wp\/v2\/media?parent=2144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}